{"id":2349,"date":"2020-07-10T13:17:54","date_gmt":"2020-07-10T11:17:54","guid":{"rendered":"https:\/\/engie-polska.pl\/?p=2349"},"modified":"2020-07-10T13:24:36","modified_gmt":"2020-07-10T11:24:36","slug":"wspieramy-gmine-jablonna","status":"publish","type":"post","link":"https:\/\/engie-polska.pl\/en\/2020\/07\/10\/wspieramy-gmine-jablonna\/","title":{"rendered":"(Polski) Wspieramy gmin\u0119 Jab\u0142onna"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/engie-polska.pl\/pl\/wp-json\/wp\/v2\/posts\/2349\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pl\" title=\"Polski\">Polish<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Polish.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>(Polski) Wspieramy gmin\u0119 Jab\u0142onna - ENGIE Polska<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/engie-polska.pl\/2020\/07\/10\/wspieramy-gmine-jablonna\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(Polski) Wspieramy gmin\u0119 Jab\u0142onna - ENGIE Polska\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Polish.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/engie-polska.pl\/2020\/07\/10\/wspieramy-gmine-jablonna\/\" \/>\n<meta property=\"og:site_name\" content=\"ENGIE Polska\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-10T11:17:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-10T11:24:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/engie-polska.pl\/wp-content\/uploads\/2020\/07\/aDSC01694-150x150.jpg\" \/>\n<meta name=\"author\" content=\"Magdalena Jaromi\u0144ska\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Magdalena Jaromi\u0144ska\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/engie-polska.pl\/2020\/07\/10\/wspieramy-gmine-jablonna\/\",\"url\":\"https:\/\/engie-polska.pl\/2020\/07\/10\/wspieramy-gmine-jablonna\/\",\"name\":\"(Polski) Wspieramy gmin\u0119 Jab\u0142onna - ENGIE Polska\",\"isPartOf\":{\"@id\":\"https:\/\/engie-polska.pl\/#website\"},\"datePublished\":\"2020-07-10T11:17:54+00:00\",\"dateModified\":\"2020-07-10T11:24:36+00:00\",\"author\":{\"@id\":\"https:\/\/engie-polska.pl\/#\/schema\/person\/7fcb3b35ea747bc7eaff117fbb3e91e8\"},\"breadcrumb\":{\"@id\":\"https:\/\/engie-polska.pl\/2020\/07\/10\/wspieramy-gmine-jablonna\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/engie-polska.pl\/2020\/07\/10\/wspieramy-gmine-jablonna\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/engie-polska.pl\/2020\/07\/10\/wspieramy-gmine-jablonna\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/engie-polska.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wspieramy gmin\u0119 Jab\u0142onna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/engie-polska.pl\/#website\",\"url\":\"https:\/\/engie-polska.pl\/\",\"name\":\"ENGIE Polska\",\"description\":\"ENGIE combines expertise in the field of energy efficiency, technical maintenance of facilities, design and construction and the production, transmission of energy and renewable energy.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/engie-polska.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/engie-polska.pl\/#\/schema\/person\/7fcb3b35ea747bc7eaff117fbb3e91e8\",\"name\":\"Magdalena Jaromi\u0144ska\",\"url\":\"https:\/\/engie-polska.pl\/en\/author\/magj_eng\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"(Polski) Wspieramy gmin\u0119 Jab\u0142onna - ENGIE Polska","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/engie-polska.pl\/2020\/07\/10\/wspieramy-gmine-jablonna\/","og_locale":"en_US","og_type":"article","og_title":"(Polski) Wspieramy gmin\u0119 Jab\u0142onna - ENGIE Polska","og_description":"Sorry, this entry is only available in Polish.","og_url":"https:\/\/engie-polska.pl\/2020\/07\/10\/wspieramy-gmine-jablonna\/","og_site_name":"ENGIE Polska","article_published_time":"2020-07-10T11:17:54+00:00","article_modified_time":"2020-07-10T11:24:36+00:00","og_image":[{"url":"https:\/\/engie-polska.pl\/wp-content\/uploads\/2020\/07\/aDSC01694-150x150.jpg"}],"author":"Magdalena Jaromi\u0144ska","twitter_card":"summary","twitter_misc":{"Written by":"Magdalena Jaromi\u0144ska"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/engie-polska.pl\/2020\/07\/10\/wspieramy-gmine-jablonna\/","url":"https:\/\/engie-polska.pl\/2020\/07\/10\/wspieramy-gmine-jablonna\/","name":"(Polski) Wspieramy gmin\u0119 Jab\u0142onna - ENGIE Polska","isPartOf":{"@id":"https:\/\/engie-polska.pl\/#website"},"datePublished":"2020-07-10T11:17:54+00:00","dateModified":"2020-07-10T11:24:36+00:00","author":{"@id":"https:\/\/engie-polska.pl\/#\/schema\/person\/7fcb3b35ea747bc7eaff117fbb3e91e8"},"breadcrumb":{"@id":"https:\/\/engie-polska.pl\/2020\/07\/10\/wspieramy-gmine-jablonna\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/engie-polska.pl\/2020\/07\/10\/wspieramy-gmine-jablonna\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/engie-polska.pl\/2020\/07\/10\/wspieramy-gmine-jablonna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/engie-polska.pl\/"},{"@type":"ListItem","position":2,"name":"Wspieramy gmin\u0119 Jab\u0142onna"}]},{"@type":"WebSite","@id":"https:\/\/engie-polska.pl\/#website","url":"https:\/\/engie-polska.pl\/","name":"ENGIE Polska","description":"ENGIE combines expertise in the field of energy efficiency, technical maintenance of facilities, design and construction and the production, transmission of energy and renewable energy.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/engie-polska.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/engie-polska.pl\/#\/schema\/person\/7fcb3b35ea747bc7eaff117fbb3e91e8","name":"Magdalena Jaromi\u0144ska","url":"https:\/\/engie-polska.pl\/en\/author\/magj_eng\/"}]}},"_links":{"self":[{"href":"https:\/\/engie-polska.pl\/en\/wp-json\/wp\/v2\/posts\/2349"}],"collection":[{"href":"https:\/\/engie-polska.pl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/engie-polska.pl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/engie-polska.pl\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/engie-polska.pl\/en\/wp-json\/wp\/v2\/comments?post=2349"}],"version-history":[{"count":5,"href":"https:\/\/engie-polska.pl\/en\/wp-json\/wp\/v2\/posts\/2349\/revisions"}],"predecessor-version":[{"id":2357,"href":"https:\/\/engie-polska.pl\/en\/wp-json\/wp\/v2\/posts\/2349\/revisions\/2357"}],"wp:attachment":[{"href":"https:\/\/engie-polska.pl\/en\/wp-json\/wp\/v2\/media?parent=2349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/engie-polska.pl\/en\/wp-json\/wp\/v2\/categories?post=2349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/engie-polska.pl\/en\/wp-json\/wp\/v2\/tags?post=2349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}